{"id":13431,"date":"2022-04-20T13:52:30","date_gmt":"2022-04-20T13:52:30","guid":{"rendered":"https:\/\/u-intosai.org\/?p=13431"},"modified":"2022-04-18T10:01:44","modified_gmt":"2022-04-18T10:01:44","slug":"orkb-brasiliens-hielt-ein-oeffentliches-treffen-das-dem-oeffentlichen-auftragswesen-gewidmet-wurde-ab","status":"publish","type":"post","link":"https:\/\/u-intosai.org\/de\/nachrichten\/orkb-brasiliens-hielt-ein-oeffentliches-treffen-das-dem-oeffentlichen-auftragswesen-gewidmet-wurde-ab\/","title":{"rendered":"ORKB Brasiliens hielt ein \u00f6ffentliches Treffen, das dem \u00f6ffentlichen Auftragswesen gewidmet wurde, ab"},"content":{"rendered":"<p>Im M\u00e4rz 2022 veranstaltete ORKB Brasiliens in Zusammenarbeit mit dem Ministerium f\u00fcr Wirtschaft und dem Ministerium f\u00fcr Wissenschaft, Technologie und Innovation eine Veranstaltung zu \u00f6ffentliches Auftragswesen von Innovationsprodukten.<\/p>\n<p>Das Treffen zielte ab, neue Produkte zur Unterst\u00fctzung von Startups (Marco Legal de Startups) im Rahmen des Staatsvertrages \u00fcber innovative L\u00f6sungen (CPSI) zu untersuchen.<\/p>\n<p>W\u00e4hrend des Treffens wurden die Untersuchungsergebnisse bez\u00fcglich der Endprodukte des Staatsvertrages \u0421PSI vorgestellt. Das Ziel der Untersuchung besteht darin, alle an \u00f6ffentliches Auftragswesen interessierten Personen zu unterst\u00fctzen und Innovationsprodukte auf den Markt zu bringen.<\/p>\n<p>Die Teilnehmer haben sich mit den Besonderheiten des CPSI-Vertrages vertraut gemacht und praktische Arbeit der kommunalen Selbstverwaltungsbeh\u00f6rden mit dem Staatsvertrag betrachtet.<\/p>\n<p><a href=\"https:\/\/portal.tcu.gov.br\/imprensa\/noticias\/evento-vai-abordar-contratacao-publica-de-solucoes-inovadoras.htm\" target=\"_blank\" rel=\"noopener\">Mehr erfahren Sie unter<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im M\u00e4rz 2022 veranstaltete ORKB Brasiliens in Zusammenarbeit mit dem Ministerium f\u00fcr Wirtschaft und dem Ministerium f\u00fcr Wissenschaft, Technologie und Innovation eine Veranstaltung zu \u00f6ffentliches Auftragswesen von Innovationsprodukten. Das Treffen zielte ab, neue Produkte zur Unterst\u00fctzung von Startups (Marco Legal de Startups) im Rahmen des Staatsvertrages \u00fcber innovative L\u00f6sungen (CPSI) zu untersuchen. W\u00e4hrend des Treffens [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[288],"tags":[1067,1066,860],"class_list":["post-13431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten","tag-efs-brasil-de","tag-apertura-de","tag-oeffentliche-beschaffung"],"acf":[],"_links":{"self":[{"href":"https:\/\/u-intosai.org\/de\/wp-json\/wp\/v2\/posts\/13431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/u-intosai.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/u-intosai.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/de\/wp-json\/wp\/v2\/comments?post=13431"}],"version-history":[{"count":1,"href":"https:\/\/u-intosai.org\/de\/wp-json\/wp\/v2\/posts\/13431\/revisions"}],"predecessor-version":[{"id":13432,"href":"https:\/\/u-intosai.org\/de\/wp-json\/wp\/v2\/posts\/13431\/revisions\/13432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/de\/wp-json\/wp\/v2\/media\/13236"}],"wp:attachment":[{"href":"https:\/\/u-intosai.org\/de\/wp-json\/wp\/v2\/media?parent=13431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/u-intosai.org\/de\/wp-json\/wp\/v2\/categories?post=13431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/u-intosai.org\/de\/wp-json\/wp\/v2\/tags?post=13431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}