{"id":28000,"date":"2023-03-22T08:50:30","date_gmt":"2023-03-22T05:50:30","guid":{"rendered":"https:\/\/u-intosai.org\/sin-categorizar\/voa-chernogorii-provel-trening-na-temu-chestnosti-i-konflikta-interesov\/"},"modified":"2023-04-03T17:47:24","modified_gmt":"2023-04-03T14:47:24","slug":"la-efs-de-montenegro-impartio-una-formacion-sobre-integridad-y-conflicto-de-intereses","status":"publish","type":"post","link":"https:\/\/u-intosai.org\/es\/noticias\/la-efs-de-montenegro-impartio-una-formacion-sobre-integridad-y-conflicto-de-intereses\/","title":{"rendered":"La EFS de Montenegro imparti\u00f3 una formaci\u00f3n sobre integridad y conflicto de intereses"},"content":{"rendered":"<p>El personal de la EFS de Montenegro <a href=\"http:\/\/www.dri.co.me\/aktuelnost\/odrzana-obuka-na-temu-integriteta-i-sukoba-interesa\">particip\u00f3<\/a> en una formaci\u00f3n sobre el tema de la integridad y el conflicto de intereses, que fue impartida por funcionarios de la Agencia para la Prevenci\u00f3n de la Corrupci\u00f3n en el marco del Plan Estrat\u00e9gico para el Desarrollo de la EFS. Durante el evento se presentaron los procedimientos y pr\u00e1cticas para el cumplimiento de las obligaciones legales en materia de integridad y prevenci\u00f3n de conflictos de intereses en el desempe\u00f1o de las funciones p\u00fablicas.<\/p>\n<p>La EFS de Montenegro se\u00f1al\u00f3 que anteriormente hab\u00eda celebrado varios eventos similares en cooperaci\u00f3n con la EFS de los Pa\u00edses Bajos.\u00a0En el pr\u00f3ximo periodo, est\u00e1 previsto llevar a cabo una formaci\u00f3n conjunta con la EFS de Croacia, que lidera la red de \u00e9tica de EUROSAI.<\/p>\n<p>Las formaciones se centrar\u00e1n en la aplicaci\u00f3n pr\u00e1ctica del C\u00f3digo \u00c9tico de INTOSAI (ISSAI 130) y la fiscalizaci\u00f3n de la \u00e9tica en los organismos del sector p\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El personal de la EFS de Montenegro particip\u00f3 en una formaci\u00f3n sobre el tema de la integridad y el conflicto de intereses, que fue impartida por funcionarios de la Agencia para la Prevenci\u00f3n de la Corrupci\u00f3n en el marco del Plan Estrat\u00e9gico para el Desarrollo de la EFS. Durante el evento se presentaron los procedimientos [&hellip;]<\/p>\n","protected":false},"author":206,"featured_media":26984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[272],"tags":[879,629,1440],"class_list":["post-28000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-anticorrupcion","tag-colaboracion","tag-sai-montenegro-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/posts\/28000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/users\/206"}],"replies":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/comments?post=28000"}],"version-history":[{"count":1,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/posts\/28000\/revisions"}],"predecessor-version":[{"id":28007,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/posts\/28000\/revisions\/28007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/media\/26984"}],"wp:attachment":[{"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/media?parent=28000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/categories?post=28000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/tags?post=28000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}