{"id":33730,"date":"2023-06-19T15:40:55","date_gmt":"2023-06-19T12:40:55","guid":{"rendered":"https:\/\/u-intosai.org\/sin-categorizar\/sai-montenegro-held-a-scientific-conference\/"},"modified":"2023-07-10T15:53:02","modified_gmt":"2023-07-10T12:53:02","slug":"la-efs-de-montenegro-ha-organizado-una-conferencia-cientifica","status":"publish","type":"post","link":"https:\/\/u-intosai.org\/es\/noticias\/la-efs-de-montenegro-ha-organizado-una-conferencia-cientifica\/","title":{"rendered":"La EFS de Montenegro ha organizado una conferencia cient\u00edfica"},"content":{"rendered":"<p>La EFS de Montenegro ha organizado <a href=\"https:\/\/dri.co.me\/aktuelnost\/naucni-skup-povodom-obiljezavanja-dana-drzavne-revizorske-institucije-crne-gore\">una conferencia cient\u00edfica<\/a> dedicada a la conmemoraci\u00f3n de la fecha de creaci\u00f3n de la EFS de Montenegro.<\/p>\n<p>Los facilitadores de la reuni\u00f3n cient\u00edfica fueron el representante de la EFS de Montenegro, Sr. Zoran Jeli\u0107, y la jefa adjunta del Programa SIGMA, Bianca Breteche.<\/p>\n<p>A la reuni\u00f3n cient\u00edfica han asistido altos funcionarios de las entidades fiscalizadoras superiores de Albania, Bosnia y Herzegovina, Kosovo, Macedonia del Norte, Eslovenia, Turqu\u00eda y Croacia.<\/p>\n<p>Durante el evento se llevaron a cabo paneles sobre los temas \u201cAuditor\u00eda del sector p\u00fablico y estabilidad financiera\u201d e \u201cInformaci\u00f3n de los resultados de las auditor\u00edas\u201d.\u00a0<\/p>\n<p>Adem\u00e1s, los participantes debatieron sobre la aplicaci\u00f3n de los ODS en las actividades de las EFS, las cuestiones de la estrategia de comunicaci\u00f3n eficaz, los cambios organizativos en la estructura de la organizaci\u00f3n y las competencias digitales de los empleados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La EFS de Montenegro ha organizado una conferencia cient\u00edfica dedicada a la conmemoraci\u00f3n de la fecha de creaci\u00f3n de la EFS de Montenegro. Los facilitadores de la reuni\u00f3n cient\u00edfica fueron el representante de la EFS de Montenegro, Sr. Zoran Jeli\u0107, y la jefa adjunta del Programa SIGMA, Bianca Breteche. A la reuni\u00f3n cient\u00edfica han asistido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33411,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[272],"tags":[629,430,1440],"class_list":["post-33730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-colaboracion","tag-ods","tag-sai-montenegro-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/posts\/33730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/comments?post=33730"}],"version-history":[{"count":1,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/posts\/33730\/revisions"}],"predecessor-version":[{"id":33864,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/posts\/33730\/revisions\/33864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/media\/33411"}],"wp:attachment":[{"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/media?parent=33730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/categories?post=33730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/tags?post=33730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}