{"id":47921,"date":"2025-07-02T16:33:09","date_gmt":"2025-07-02T13:33:09","guid":{"rendered":"https:\/\/u-intosai.org\/sin-categorizar\/sai-philippines-conducted-a-continuing-legal-education-program\/"},"modified":"2025-07-16T21:12:59","modified_gmt":"2025-07-16T18:12:59","slug":"la-efs-de-filipinas-lleva-a-cabo-un-programa-de-educacion-juridica-continua","status":"publish","type":"post","link":"https:\/\/u-intosai.org\/es\/noticias\/la-efs-de-filipinas-lleva-a-cabo-un-programa-de-educacion-juridica-continua\/","title":{"rendered":"La EFS de Filipinas lleva a cabo un programa de educaci\u00f3n jur\u00eddica continua"},"content":{"rendered":"<p>La EFS de Filipinas <a href=\"https:\/\/www.coa.gov.ph\/coa-conducts-8th-mandatory-continuing-legal-education-compliance-program\/\">llev\u00f3 a cabo<\/a> el octavo programa de Educaci\u00f3n Jur\u00eddica Continua Obligatoria (MCLE) en el Centro de Capacitaci\u00f3n Internacional de la EFS en la ciudad de Tagaytay.<\/p>\n<p>El programa est\u00e1 dise\u00f1ado para profundizar el conocimiento de las nuevas normativas legales, fomentar el cumplimiento de los est\u00e1ndares \u00e9ticos y fortalecer las competencias en los \u00e1mbitos de la auditor\u00eda y la administraci\u00f3n p\u00fablica.<\/p>\n<p>Durante la capacitaci\u00f3n, los participantes analizaron las decisiones judiciales m\u00e1s recientes, los cambios legislativos y los nuevos enfoques en la pr\u00e1ctica jur\u00eddica.<\/p>\n<p>Esta formaci\u00f3n se lleva a cabo cada tres a\u00f1os y permite reunir a funcionarios legalmente habilitados de la EFS provenientes de distintas regiones del pa\u00eds, lo que a su vez ofrece una valiosa oportunidad de desarrollo profesional e intercambio de experiencias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La EFS de Filipinas llev\u00f3 a cabo el octavo programa de Educaci\u00f3n Jur\u00eddica Continua Obligatoria (MCLE) en el Centro de Capacitaci\u00f3n Internacional de la EFS en la ciudad de Tagaytay. El programa est\u00e1 dise\u00f1ado para profundizar el conocimiento de las nuevas normativas legales, fomentar el cumplimiento de los est\u00e1ndares \u00e9ticos y fortalecer las competencias en [&hellip;]<\/p>\n","protected":false},"author":206,"featured_media":47821,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[272],"tags":[618,1996,616],"class_list":["post-47921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-desarrollo-de-capacidad","tag-efs-de-filipinas","tag-apertura"],"acf":[],"_links":{"self":[{"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/posts\/47921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/users\/206"}],"replies":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/comments?post=47921"}],"version-history":[{"count":2,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/posts\/47921\/revisions"}],"predecessor-version":[{"id":48037,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/posts\/47921\/revisions\/48037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/media\/47821"}],"wp:attachment":[{"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/media?parent=47921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/categories?post=47921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/u-intosai.org\/es\/wp-json\/wp\/v2\/tags?post=47921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}