{"id":17091,"date":"2022-07-08T20:46:14","date_gmt":"2022-07-08T17:46:14","guid":{"rendered":"https:\/\/u-intosai.org\/?p=17091"},"modified":"2022-06-15T14:23:24","modified_gmt":"2022-06-15T11:23:24","slug":"olacefs-cree-une-banque-de-donnees-audiovisuelles","status":"publish","type":"post","link":"https:\/\/u-intosai.org\/fr\/nouvelles\/olacefs-cree-une-banque-de-donnees-audiovisuelles\/","title":{"rendered":"OLACEFS cr\u00e9e une banque de donn\u00e9es audiovisuelles"},"content":{"rendered":"<p>En mai, la Commission technique sur les bonnes pratiques de gouvernance de l\u2019Organisation des institutions sup\u00e9rieures de contr\u00f4le des finances publiques d\u2019Am\u00e9rique latine et des Cara\u00efbes (OLACEFS) <a href=\"https:\/\/www.agn.gob.ar\/actualidad-institucional\/registrar-la-experiencia-una-buena-practica\">a organis\u00e9<\/a> une r\u00e9union sur les communications internes de la r\u00e9gion OLACEFS. Au cours de la r\u00e9union, la cr\u00e9ation d\u2019une banque audiovisuelle a \u00e9t\u00e9 discut\u00e9e.<\/p>\n<p>La commission technique cherche \u00e0 renforcer la communication entre les organisations participantes depuis 2019. Plusieurs documents ont \u00e9t\u00e9 \u00e9labor\u00e9s dans le cadre de ce projet, notamment une cartographie sch\u00e9matique des m\u00e9canismes de communication dans la r\u00e9gion et des enqu\u00eates sur l\u2019impact de COVID-19 sur la communication de crise.<\/p>\n<p>En 2022, les membres de la Commission travailleront \u00e0 d\u00e9velopper et \u00e0 alimenter la banque en mat\u00e9riel audiovisuel. La banque sera affich\u00e9e sur le canal officiel d\u2019OLACEFS. Les ISC int\u00e9ress\u00e9s pourront consulter les documents de la banque et b\u00e9n\u00e9ficier des bonnes pratiques de communication.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En mai, la Commission technique sur les bonnes pratiques de gouvernance de l\u2019Organisation des institutions sup\u00e9rieures de contr\u00f4le des finances publiques d\u2019Am\u00e9rique latine et des Cara\u00efbes (OLACEFS) a organis\u00e9 une r\u00e9union sur les communications internes de la r\u00e9gion OLACEFS. Au cours de la r\u00e9union, la cr\u00e9ation d\u2019une banque audiovisuelle a \u00e9t\u00e9 discut\u00e9e. La commission technique [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[287],"tags":[1209,1193,1106,1021,1068],"class_list":["post-17091","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-communication-fr","tag-regional-cooperation-fr","tag-desarrollo-regional-fr","tag-olacefs-fr","tag-apertura-de-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/posts\/17091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/comments?post=17091"}],"version-history":[{"count":2,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/posts\/17091\/revisions"}],"predecessor-version":[{"id":17093,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/posts\/17091\/revisions\/17093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/media\/15184"}],"wp:attachment":[{"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/media?parent=17091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/categories?post=17091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/tags?post=17091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}