{"id":27857,"date":"2023-03-03T17:27:26","date_gmt":"2023-03-03T14:27:26","guid":{"rendered":"https:\/\/u-intosai.org\/non-classifiee\/sai-moldova-and-sai-latvia-exchanged-experience-in-the-field-of-state-budget-audit\/"},"modified":"2023-04-03T14:59:15","modified_gmt":"2023-04-03T11:59:15","slug":"les-isc-de-moldova-et-de-lettonie-echangent-leurs-experiences-en-matiere-daudit-du-budget-public","status":"publish","type":"post","link":"https:\/\/u-intosai.org\/fr\/nouvelles\/les-isc-de-moldova-et-de-lettonie-echangent-leurs-experiences-en-matiere-daudit-du-budget-public\/","title":{"rendered":"Les ISC de Moldova et de Lettonie \u00e9changent leurs exp\u00e9riences en mati\u00e8re d&rsquo;audit du budget public"},"content":{"rendered":"<p>Les ISC de Moldova et de Lettonie <a href=\"https:\/\/www.ccrm.md\/ro\/atelier-privind-bunele-practici-internationale-in-domeniul-auditului-bugetului-80_92641.html\">ont mis en place<\/a> un webinaire afin d&rsquo;\u00e9changer les meilleures pratiques en mati\u00e8re d&rsquo;audit du budget public.<\/p>\n<p>Ce s\u00e9minaire a \u00e9t\u00e9 organis\u00e9 dans le cadre d&rsquo;initiatives de coop\u00e9ration entre les deux institutions en vue de renforcer les capacit\u00e9s et de promouvoir de meilleures pratiques internationales en mati\u00e8re d&rsquo;\u00e9tablissement de rapports sur le budget public conform\u00e9ment aux normes internationales.<\/p>\n<p>Les repr\u00e9sentants des institutions ont convenu de poursuivre la coop\u00e9ration et l&rsquo;\u00e9change d&rsquo;exp\u00e9riences afin d&rsquo;aborder les aspects les plus importants li\u00e9s \u00e0 l&rsquo;audit du budget public en vue de cr\u00e9er un projet de document pertinent pour les contr\u00f4leurs qui incorporerait de meilleures pratiques et prendrait en compte les sp\u00e9cificit\u00e9s nationales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les ISC de Moldova et de Lettonie ont mis en place un webinaire afin d&rsquo;\u00e9changer les meilleures pratiques en mati\u00e8re d&rsquo;audit du budget public. Ce s\u00e9minaire a \u00e9t\u00e9 organis\u00e9 dans le cadre d&rsquo;initiatives de coop\u00e9ration entre les deux institutions en vue de renforcer les capacit\u00e9s et de promouvoir de meilleures pratiques internationales en mati\u00e8re d&rsquo;\u00e9tablissement [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[287],"tags":[851,820,1410],"class_list":["post-27857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-isc-de-moldavie","tag-partenariat","tag-sai-latvia-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/posts\/27857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/comments?post=27857"}],"version-history":[{"count":2,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/posts\/27857\/revisions"}],"predecessor-version":[{"id":27865,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/posts\/27857\/revisions\/27865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/media\/26870"}],"wp:attachment":[{"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/media?parent=27857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/categories?post=27857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/tags?post=27857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}