{"id":41680,"date":"2023-11-24T18:43:47","date_gmt":"2023-11-24T15:43:47","guid":{"rendered":"https:\/\/u-intosai.org\/non-classifiee\/sotrudnik-voa-moldovy-proshla-stazhirovku-v-evropejskoj-schetnoj-palate\/"},"modified":"2023-12-27T16:17:41","modified_gmt":"2023-12-27T13:17:41","slug":"une-employee-de-lisc-de-moldavie-a-passe-un-stage-a-la-cour-des-comptes-europeenne","status":"publish","type":"post","link":"https:\/\/u-intosai.org\/fr\/nouvelles\/une-employee-de-lisc-de-moldavie-a-passe-un-stage-a-la-cour-des-comptes-europeenne\/","title":{"rendered":"Une employ\u00e9e de l\u2019ISC de Moldavie a pass\u00e9 un stage \u00e0 la Cour des comptes europ\u00e9enne"},"content":{"rendered":"<p>Une employ\u00e9e moldave a <a href=\"https:\/\/www.ccrm.md\/ro\/auditoarea-ccrm-a-finalizat-stagiul-la-curtea-de-conturi-80_92982.html\">termin\u00e9<\/a> avec succ\u00e8s un programme de stage de 5\u00a0mois \u00e0 la Cour des comptes europ\u00e9enne.<\/p>\n<p>L\u2019objectif du programme est l\u2019\u00e9change d\u2019exp\u00e9riences entre les institutions sup\u00e9rieures de contr\u00f4le en vue de l\u2019adh\u00e9sion \u00e0 l\u2019Union europ\u00e9enne.<\/p>\n<p>Mme Marina Kataraga, inspectrice de l\u2019ISC de Moldavie, est devenue la premi\u00e8re participante au programme. Au cours du stage elle s\u2019est familiaris\u00e9e avec les aspects th\u00e9oriques et pratiques du processus d\u2019audit, de la strat\u00e9gie et de la m\u00e9thodologie d\u2019audit de la Cour des comptes europ\u00e9enne.\u00a0Durant le stage \u00e9galement l\u2019inspecteur a particip\u00e9 \u00e0 des travaux d\u2019audit en collaboration avec les inspecteurs de la Cour des comptes europ\u00e9enne.<\/p>\n<p>En outre, Mme Kataraga a eu l\u2019occasion de partager ses connaissances et son exp\u00e9rience avec d\u2019autres participants aux stages des ISC d\u2019Albanie, de Serbie et de Turquie.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une employ\u00e9e moldave a termin\u00e9 avec succ\u00e8s un programme de stage de 5\u00a0mois \u00e0 la Cour des comptes europ\u00e9enne. L\u2019objectif du programme est l\u2019\u00e9change d\u2019exp\u00e9riences entre les institutions sup\u00e9rieures de contr\u00f4le en vue de l\u2019adh\u00e9sion \u00e0 l\u2019Union europ\u00e9enne. Mme Marina Kataraga, inspectrice de l\u2019ISC de Moldavie, est devenue la premi\u00e8re participante au programme. Au cours [&hellip;]<\/p>\n","protected":false},"author":206,"featured_media":37842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[287],"tags":[1690,851,820],"class_list":["post-41680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-eca-fr","tag-isc-de-moldavie","tag-partenariat"],"acf":[],"_links":{"self":[{"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/posts\/41680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/users\/206"}],"replies":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/comments?post=41680"}],"version-history":[{"count":1,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/posts\/41680\/revisions"}],"predecessor-version":[{"id":41786,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/posts\/41680\/revisions\/41786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/media\/37842"}],"wp:attachment":[{"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/media?parent=41680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/categories?post=41680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/u-intosai.org\/fr\/wp-json\/wp\/v2\/tags?post=41680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}