{"id":13427,"date":"2022-04-20T13:52:30","date_gmt":"2022-04-20T13:52:30","guid":{"rendered":"https:\/\/u-intosai.org\/?p=13427"},"modified":"2022-04-18T09:57:49","modified_gmt":"2022-04-18T09:57:49","slug":"a-efs-do-brasil-realizou-uma-reuniao-aberta-sobre-contratacoes-publicas","status":"publish","type":"post","link":"https:\/\/u-intosai.org\/pt-pt\/noticia\/a-efs-do-brasil-realizou-uma-reuniao-aberta-sobre-contratacoes-publicas\/","title":{"rendered":"A EFS do Brasil realizou uma reuni\u00e3o aberta sobre contrata\u00e7\u00f5es p\u00fablicas"},"content":{"rendered":"<p>Em mar\u00e7o de 2022, a EFS do Brasil, em conjunto com o Minist\u00e9rio da Economia e o Minist\u00e9rio da Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o, realizou um evento dedicado \u00e0s contrata\u00e7\u00f5es p\u00fablicas de produtos inovadores.<\/p>\n<p>O prop\u00f3sito do encontro era estudar novos produtos de apoio \u00e0s startups (Marco Legal de Startups) no \u00e2mbito do contrato p\u00fablico de solu\u00e7\u00f5es inovadoras (CPSI).<\/p>\n<p>Durante o encontro, foram apresentados os resultados de um estudo sobre os produtos finais do contrato p\u00fablico do CPSI. O prop\u00f3sito do estudo \u00e9 apoiar todas as partes interessadas na contrata\u00e7\u00e3o p\u00fablica e na introdu\u00e7\u00e3o de produtos inovadores.<\/p>\n<p>Os participantes conheceram as caracter\u00edsticas do contrato CPSI e estudaram exemplos pr\u00e1ticos de atua\u00e7\u00e3o das prefeituras com contrato p\u00fablico.<\/p>\n<p><a href=\"https:\/\/portal.tcu.gov.br\/imprensa\/noticias\/evento-vai-abordar-contratacao-publica-de-solucoes-inovadoras.htm\" target=\"_blank\" rel=\"noopener\">Leia mais<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em mar\u00e7o de 2022, a EFS do Brasil, em conjunto com o Minist\u00e9rio da Economia e o Minist\u00e9rio da Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o, realizou um evento dedicado \u00e0s contrata\u00e7\u00f5es p\u00fablicas de produtos inovadores. O prop\u00f3sito do encontro era estudar novos produtos de apoio \u00e0s startups (Marco Legal de Startups) no \u00e2mbito do contrato p\u00fablico de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13237,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[652],"tags":[1065,857,881],"class_list":["post-13427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","tag-openness-pt-pt","tag-contratatacao-publica","tag-efs-do-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/posts\/13427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=13427"}],"version-history":[{"count":1,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/posts\/13427\/revisions"}],"predecessor-version":[{"id":13428,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/posts\/13427\/revisions\/13428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/media\/13237"}],"wp:attachment":[{"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=13427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=13427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=13427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}