{"id":16999,"date":"2022-06-01T17:37:53","date_gmt":"2022-06-01T14:37:53","guid":{"rendered":"https:\/\/u-intosai.org\/sem-categoria\/mes-del-desarrollo-sostenible-en-brasil\/"},"modified":"2022-06-15T12:07:16","modified_gmt":"2022-06-15T09:07:16","slug":"mes-da-sustentabilidade-no-brasil","status":"publish","type":"post","link":"https:\/\/u-intosai.org\/pt-pt\/noticia\/mes-da-sustentabilidade-no-brasil\/","title":{"rendered":"M\u00eas da Sustentabilidade no Brasil"},"content":{"rendered":"<p>A Rede Brasileira de Legisla\u00e7\u00e3o Sustent\u00e1vel oferece o \u201cM\u00eas da Sustentabilidade\u201d em junho.<\/p>\n<p>Durante um m\u00eas, uma s\u00e9rie de eventos virtuais sobre governan\u00e7a sustent\u00e1vel ser\u00e1 realizada.<\/p>\n<p>A EFS do Brasil, juntamente com a Rede de Direito Sustent\u00e1vel, lan\u00e7ar\u00e1 uma s\u00e9rie de webinars sobre governan\u00e7a sustent\u00e1vel. No dia 9 de junho ser\u00e1 realizado o primeiro webinar com a participa\u00e7\u00e3o da Presidente da EFS do Brasil, Sra. Ana Arraes.<\/p>\n<p>Os detalhes da conex\u00e3o podem ser encontrados na se\u00e7\u00e3o \u201c<a href=\"https:\/\/u-intosai.org\/ru\/event\/seriya-vebinarov-voa-brazilii-po-ustojchivomu-gosudarstvennomu-upravleniyu\/\">Eventos<\/a>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Rede Brasileira de Legisla\u00e7\u00e3o Sustent\u00e1vel oferece o \u201cM\u00eas da Sustentabilidade\u201d em junho. Durante um m\u00eas, uma s\u00e9rie de eventos virtuais sobre governan\u00e7a sustent\u00e1vel ser\u00e1 realizada. A EFS do Brasil, juntamente com a Rede de Direito Sustent\u00e1vel, lan\u00e7ar\u00e1 uma s\u00e9rie de webinars sobre governan\u00e7a sustent\u00e1vel. No dia 9 de junho ser\u00e1 realizado o primeiro webinar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[652],"tags":[1174,881,784],"class_list":["post-16999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","tag-communication-pt-pt","tag-efs-do-brasil","tag-ods-pt-pt"],"acf":[],"_links":{"self":[{"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/posts\/16999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=16999"}],"version-history":[{"count":2,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/posts\/16999\/revisions"}],"predecessor-version":[{"id":17001,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/posts\/16999\/revisions\/17001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/media\/14952"}],"wp:attachment":[{"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=16999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=16999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=16999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}