{"id":27151,"date":"2022-12-16T23:06:31","date_gmt":"2022-12-16T20:06:31","guid":{"rendered":"https:\/\/u-intosai.org\/sem-categoria\/xiii-conference-on-debt-management\/"},"modified":"2023-03-21T14:27:06","modified_gmt":"2023-03-21T11:27:06","slug":"xiii-conferencia-sobre-gestao-de-dividas","status":"publish","type":"post","link":"https:\/\/u-intosai.org\/pt-pt\/noticia\/xiii-conferencia-sobre-gestao-de-dividas\/","title":{"rendered":"XIII Confer\u00eancia Sobre Gest\u00e3o de D\u00edvidas"},"content":{"rendered":"<p>Em Dezembro,<a href=\"https:\/\/sai.gov.az\/xeberler\/208\"> realizou-se<\/a> a XIII Confer\u00eancia sobre Gest\u00e3o da D\u00edvida da Confer\u00eancia das Na\u00e7\u00f5es Unidas sobre Com\u00e9rcio e Desenvolvimento (UNCTAD), em Genebra, Su\u00ed\u00e7a, de 5-7 de Dezembro de 2022.<\/p>\n<p>A Confer\u00eancia contou com a presen\u00e7a da ISA do Azerbaij\u00e3o, Ge\u00f3rgia, Ar\u00e1bia Saudita, It\u00e1lia, Espanha, Brasil, Quirguist\u00e3o, bem como de representantes do sector privado.<\/p>\n<p>Durante a confer\u00eancia de pequenos grupos foram abordados 9 t\u00f3picos diferentes, tais como: crises da d\u00edvida nos pa\u00edses em desenvolvimento e experi\u00eancias recentes de resolu\u00e7\u00e3o da d\u00edvida, m\u00faltiplos aspectos da avalia\u00e7\u00e3o da sustentabilidade da d\u00edvida, transpar\u00eancia da d\u00edvida como bem p\u00fablico, e vis\u00e3o geral dos credores e mutu\u00e1rios.<\/p>\n<p>Os pain\u00e9is analisaram a gest\u00e3o da d\u00edvida, aumentando as vulnerabilidades econ\u00f3micas, financeiras e da d\u00edvida devido ao r\u00e1pido agravamento das crises ambientais e clim\u00e1ticas e \u00e0 pandemia global de Covid-19, bem como avaliando a sustentabilidade da d\u00edvida num ambiente de baixo retorno.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em Dezembro, realizou-se a XIII Confer\u00eancia sobre Gest\u00e3o da D\u00edvida da Confer\u00eancia das Na\u00e7\u00f5es Unidas sobre Com\u00e9rcio e Desenvolvimento (UNCTAD), em Genebra, Su\u00ed\u00e7a, de 5-7 de Dezembro de 2022. A Confer\u00eancia contou com a presen\u00e7a da ISA do Azerbaij\u00e3o, Ge\u00f3rgia, Ar\u00e1bia Saudita, It\u00e1lia, Espanha, Brasil, Quirguist\u00e3o, bem como de representantes do sector privado. Durante a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26538,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[652],"tags":[771,784,834],"class_list":["post-27151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","tag-evento-pt-pt","tag-ods-pt-pt","tag-onu-pt-pt"],"acf":[],"_links":{"self":[{"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/posts\/27151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=27151"}],"version-history":[{"count":2,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/posts\/27151\/revisions"}],"predecessor-version":[{"id":27153,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/posts\/27151\/revisions\/27153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/media\/26538"}],"wp:attachment":[{"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=27151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=27151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/u-intosai.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=27151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}